{"id":21490,"date":"2026-03-12T17:08:02","date_gmt":"2026-03-12T17:08:02","guid":{"rendered":"https:\/\/conilvacacioneslola.es\/?post_type=project&#038;p=21490"},"modified":"2026-03-12T17:08:03","modified_gmt":"2026-03-12T17:08:03","slug":"apartamento-la-bodega","status":"publish","type":"project","link":"https:\/\/conilvacacioneslola.es\/index.php\/project\/apartamento-la-bodega\/","title":{"rendered":"Apartamento La Bodega"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21490\" class=\"elementor elementor-21490\" data-elementor-post-type=\"project\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc367b4 e-con-full e-flex e-con e-parent\" data-id=\"7fc367b4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-69e2cc87 e-flex e-con-boxed e-con e-child\" data-id=\"69e2cc87\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d33f973 elementor-widget__width-initial content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"6d33f973\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1600\" height=\"1066\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%201066&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 1066;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/OL.jpeg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/OL.jpeg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/OL-300x200.jpeg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/OL-1024x682.jpeg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/OL-768x512.jpeg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/OL-1536x1023.jpeg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b5f73ce elementor-widget__width-initial content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"7b5f73ce\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"1066\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%201066&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 1066;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-10-at-12.02.14.jpeg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-10-at-12.02.14.jpeg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-10-at-12.02.14-300x200.jpeg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-10-at-12.02.14-1024x682.jpeg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-10-at-12.02.14-768x512.jpeg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/WhatsApp-Image-2026-03-10-at-12.02.14-1536x1023.jpeg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-180c6e4e e-flex e-con-boxed e-con e-child\" data-id=\"180c6e4e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-393817c8 e-con-full e-flex e-con e-child\" data-id=\"393817c8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43d6a412 elementor-widget elementor-widget-the7-heading\" data-id=\"43d6a412\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"the7-heading-title elementor-size-default\">Apartamento La Bodega<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11481dbf elementor-widget elementor-widget-text-editor\" data-id=\"11481dbf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Acogedor apartamento vacacional situado en Calle Bodega, a tan solo 7 minutos andando de la playa, ideal para quienes buscan disfrutar del mar y la tranquilidad durante sus vacaciones.<\/p><p>La vivienda cuenta con dos dormitorios, cocina abierta al sal\u00f3n totalmente equipada con horno, microondas y lavavajillas, adem\u00e1s de un ba\u00f1o completo. Dispone de aire acondicionado y chimenea, ofreciendo comodidad tanto en verano como en \u00e9pocas m\u00e1s frescas.<\/p><p>El apartamento tambi\u00e9n incluye plaza de garaje, piscina comunitaria perfecta para refrescarse en los d\u00edas de sol y terraza compartida para disfrutar del aire libre.<\/p><p>Una opci\u00f3n perfecta para vacaciones cerca de la playa, con todas las comodidades necesarias para una estancia agradable.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-336ce2c6 e-con-full e-flex e-con e-child\" data-id=\"336ce2c6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-712c4cba elementor-widget elementor-widget-the7-heading\" data-id=\"712c4cba\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"the7-heading-title elementor-size-default\">Datos<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60f06985 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"60f06985\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2 Dormitorios<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 ba\u00f1o<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Piscina comunitaria + terraza compartida<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aire acondicionado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chimenea<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cocina\/Sal\u00f3n<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lavavajillas, horno y microondas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garaje<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3184391c e-flex e-con-boxed e-con e-child\" data-id=\"3184391c\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39fc8007 content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"39fc8007\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"1066\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%201066&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 1066;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KMJ.jpeg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KMJ.jpeg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KMJ-300x200.jpeg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KMJ-1024x682.jpeg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KMJ-768x512.jpeg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KMJ-1536x1023.jpeg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c9ca9aa e-flex e-con-boxed e-con e-child\" data-id=\"4c9ca9aa\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d519f45 content-align-left the7-hover-visibility-disabled transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"d519f45\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"1066\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%201066&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 1066;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KK.jpeg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KK.jpeg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KK-300x200.jpeg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KK-1024x682.jpeg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KK-768x512.jpeg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/KK-1536x1023.jpeg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a918077 content-align-left the7-hover-visibility-disabled transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"5a918077\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"1066\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%201066&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 1066;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LL.jpeg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LL.jpeg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LL-300x200.jpeg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LL-1024x682.jpeg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LL-768x512.jpeg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LL-1536x1023.jpeg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5ddecab6 e-flex e-con-boxed e-con e-parent\" data-id=\"5ddecab6\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bddb776 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"5bddb776\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LKM.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LON.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/MM.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/Wha.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/\u00b4N.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/B.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/CAMA.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/D.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-thumbnails-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LKM.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/LON.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/MM.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/Wha.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/\u00b4N.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/B.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/CAMA.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2026\/03\/D.jpeg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96e8477 e-flex e-con-boxed e-con e-parent\" data-id=\"96e8477\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1679399 e-flex e-con-boxed e-con e-parent\" data-id=\"1679399\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-659adfd elementor-widget elementor-widget-google_maps\" data-id=\"659adfd\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Calle%20Bodega%2C%20Conil%20de%20la%20FRontera&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Calle Bodega, Conil de la FRontera\"\n\t\t\t\t\taria-label=\"Calle Bodega, Conil de la FRontera\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Apartamento La Bodega Acogedor apartamento vacacional situado en Calle Bodega, a tan solo 7 minutos andando de la playa, ideal para quienes buscan disfrutar del mar y la tranquilidad durante sus vacaciones. La vivienda cuenta con dos dormitorios, cocina abierta al sal\u00f3n totalmente equipada con horno, microondas y lavavajillas, adem\u00e1s de un ba\u00f1o completo. Dispone&hellip;<\/p>\n","protected":false},"featured_media":21497,"template":"","meta":[],"project_category":[126,121],"class_list":["post-21490","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-2-dormitorios","project_category-apartamentos"],"_links":{"self":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project\/21490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/types\/project"}],"version-history":[{"count":4,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project\/21490\/revisions"}],"predecessor-version":[{"id":21508,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project\/21490\/revisions\/21508"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/media\/21497"}],"wp:attachment":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/media?parent=21490"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project_category?post=21490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}