{"id":21246,"date":"2025-02-28T12:17:06","date_gmt":"2025-02-28T12:17:06","guid":{"rendered":"https:\/\/conilvacacioneslola.es\/?post_type=project&#038;p=21246"},"modified":"2025-02-28T14:59:04","modified_gmt":"2025-02-28T14:59:04","slug":"villas-santa-ana-2","status":"publish","type":"project","link":"https:\/\/conilvacacioneslola.es\/index.php\/project\/villas-santa-ana-2\/","title":{"rendered":"Villas Santa Ana 2"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21246\" class=\"elementor elementor-21246\" data-elementor-post-type=\"project\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb38a9d e-con-full e-flex e-con e-parent\" data-id=\"eb38a9d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-48a7fa5b e-flex e-con-boxed e-con e-child\" data-id=\"48a7fa5b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2ab2076d elementor-widget__width-initial content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"2ab2076d\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201024%20768&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" style=\"--ratio: 1024 \/ 768;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0057-1.jpg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0057-1.jpg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0057-1-300x225.jpg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0057-1-768x576.jpg 768w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ebdda95 elementor-widget__width-initial content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"2ebdda95\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201024%20768&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1024px) 100vw, 1024px\" style=\"--ratio: 1024 \/ 768;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0054.jpg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0054.jpg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0054-300x225.jpg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0054-768x576.jpg 768w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48421c4 e-flex e-con-boxed e-con e-child\" data-id=\"48421c4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7199a7d1 e-con-full e-flex e-con e-child\" data-id=\"7199a7d1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67c409d6 elementor-widget elementor-widget-text-editor\" data-id=\"67c409d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Este alojamiento se puede alquilar de manera individual o alquilar el complejo completo formado por <a href=\"https:\/\/conilvacacioneslola.es\/index.php\/project\/villas-santa-ana-1\/\">Villas Santa Ana 1<\/a>, <a href=\"https:\/\/conilvacacioneslola.es\/index.php\/project\/villas-santa-ana-2\/\">Villas Santa Ana 2<\/a> y<a href=\"https:\/\/conilvacacioneslola.es\/index.php\/project\/villas-santa-ana-3\/\"> Villas Santa Ana 3<\/a>.<\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8344bb2 e-flex e-con-boxed e-con e-child\" data-id=\"8344bb2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-765f1d3 e-con-full e-flex e-con e-child\" data-id=\"765f1d3\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8bbfe3 elementor-widget elementor-widget-the7-heading\" data-id=\"e8bbfe3\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"the7-heading-title elementor-size-default\">Villas Santa Ana 2<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5865e18 elementor-widget elementor-widget-text-editor\" data-id=\"5865e18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tEstupendo chalet en Conil con piscina situado a unos 10 minutos de Conil en coche, en una zona tranquila y bien comunicada. Ver mapa de situaci\u00f3n pulsando el mapa.\n\nResumen de caracter\u00edsticas de la casa:\nUbicaci\u00f3n: Parcela amplia y vallada, a 3 minutos de la carretera Nacional 340, cerca de la zona comercial de El Colorado, bien comunicada con playas como El Palmar y La Torre del Puerco en Roche, cerca de Chiclana.\nInterior: Sal\u00f3n-cocina, 1 dormitorio con cama doble,  1 cuarto de ba\u00f1o, patio privado con barbacoa.\nCocina: Completamente equipada.\nComodidades: Nueva construcci\u00f3n, mobiliario de calidad, aire acondicionado, wifi interior y exterior, ropa de cama y ba\u00f1o, aparcamiento privado.\nExterior: Jard\u00edn amplio con merendero, piscina compartida con 3 casas.\nAdecuado para: Familias o parejas.\nPol\u00edtica de mascotas: Se permiten animales de compa\u00f1\u00eda previo contacto.\nSe encuentra en una amplia parcela con c\u00e9sped y totalmente vallada. A 3 minutos de la carretera Nacional 340, a unos 800 metros de la zona comercial y de servicios de El Colorado. Est\u00e1 muy bien comunicada, por lo que podr\u00e1 visitar cualquier playa cercana, como la playa del Palmar o la playa de La Torre del Puerco en Roche, cerca de Chiclana.\n\nLa piscina es compartida con 3 casas.\n\nEs una casa en alquiler de vacaciones perfecta para familias o parejas que deseen pasar el verano en una estupenda zona de la provincia de C\u00e1diz.\n\nSe permiten animales de compa\u00f1\u00eda, pero antes debe de contactar con nosotros.\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c8ea75 e-con-full e-flex e-con e-child\" data-id=\"1c8ea75\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-21b8c71 elementor-widget elementor-widget-the7-heading\" data-id=\"21b8c71\" data-element_type=\"widget\" data-widget_type=\"the7-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"the7-heading-title elementor-size-default\">Datos<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e66794e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e66794e\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1 Dormitorio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Campo<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Piscina<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Jard\u00edn<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">WiFi<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aire acondicionado<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Admite mascotas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Barbacoa<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2332a27b e-flex e-con-boxed e-con e-child\" data-id=\"2332a27b\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1f0b398 content-align-left the7-hover-visibility-disabled preserve-img-ratio-cover transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"1f0b398\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"900\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%20900&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 900;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0081.jpg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0081.jpg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0081-300x169.jpg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0081-1024x576.jpg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0081-768x432.jpg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0081-1536x864.jpg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1923bbc7 e-flex e-con-boxed e-con e-child\" data-id=\"1923bbc7\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-42a6ccf3 content-align-left the7-hover-visibility-disabled transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"42a6ccf3\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"900\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%20900&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 900;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0082.jpg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0082.jpg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0082-300x169.jpg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0082-1024x576.jpg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0082-768x432.jpg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0082-1536x864.jpg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e8bf63a content-align-left the7-hover-visibility-disabled transform-overlay-yes exceeding-frame-yes elementor-widget elementor-widget-the7-image-widget\" data-id=\"1e8bf63a\" data-element_type=\"widget\" data-settings=\"{&quot;hover_visibility&quot;:&quot;disabled&quot;}\" data-widget_type=\"the7-image-widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"the7-image-container\"><div class=\"the7-image-wrapper the7-elementor-widget the7-transform-container\"><div class=\"post-thumbnail-rollover layzr-bg img-css-resize-wrapper\"><img decoding=\"async\" width=\"1600\" height=\"900\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039;%20viewBox%3D&#039;0%200%201600%20900&#039;%2F%3E\" class=\"attachment-full size-full preload-me aspect lazy lazy-load\" alt=\"\" sizes=\"(max-width: 1600px) 100vw, 1600px\" style=\"--ratio: 1600 \/ 900;\" data-src=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0083.jpg\" loading=\"eager\" data-srcset=\"https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0083.jpg 1600w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0083-300x169.jpg 300w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0083-1024x576.jpg 1024w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0083-768x432.jpg 768w, https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0083-1536x864.jpg 1536w\" \/><\/div><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b103593 e-flex e-con-boxed e-con e-parent\" data-id=\"5b103593\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-79dd0dde elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"79dd0dde\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-main-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0077.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0072.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0079.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0080.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0084.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0086.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0090.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0091.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0093.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0097.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Previous<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Next<\/span>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t<div class=\"elementor-thumbnails-swiper swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0077.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0072.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0079.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0080.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0084.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0086.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0090.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0091.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0093.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"\" style=\"background-image: url(&#039;https:\/\/conilvacacioneslola.es\/wp-content\/uploads\/2025\/02\/IMG-20241129-WA0097.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Este alojamiento se puede alquilar de manera individual o alquilar el complejo completo formado por Villas Santa Ana 1, Villas Santa Ana 2 y Villas Santa Ana 3. Villas Santa Ana 2 Estupendo chalet en Conil con piscina situado a unos 10 minutos de Conil en coche, en una zona tranquila y bien comunicada. Ver&hellip;<\/p>\n","protected":false},"featured_media":21247,"template":"","meta":[],"project_category":[129,122],"class_list":["post-21246","project","type-project","status-publish","has-post-thumbnail","hentry","project_category-1-dormitorio","project_category-chalet"],"_links":{"self":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project\/21246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project"}],"about":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/types\/project"}],"version-history":[{"count":10,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project\/21246\/revisions"}],"predecessor-version":[{"id":21310,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project\/21246\/revisions\/21310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/media\/21247"}],"wp:attachment":[{"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/media?parent=21246"}],"wp:term":[{"taxonomy":"project_category","embeddable":true,"href":"https:\/\/conilvacacioneslola.es\/index.php\/wp-json\/wp\/v2\/project_category?post=21246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}